{"id":22102,"date":"2024-04-25T13:39:43","date_gmt":"2024-04-25T11:39:43","guid":{"rendered":"https:\/\/czerwonagora.pl\/?p=22102"},"modified":"2024-04-26T14:18:51","modified_gmt":"2024-04-26T12:18:51","slug":"posilek-w-dniu-2024-04-25","status":"publish","type":"post","link":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/","title":{"rendered":"Posi\u0142ek w dniu 2024-04-25"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"22102\" class=\"elementor elementor-22102\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88a433d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88a433d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f23834\" data-id=\"9f23834\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2740bbf elementor-widget elementor-widget-heading\" data-id=\"2740bbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u015aniadanie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cf845cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf845cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-aaa2cbc\" data-id=\"aaa2cbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a307c2 elementor-widget elementor-widget-image\" data-id=\"4a307c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Swb-17-1024x768.jpg\" class=\"attachment-large size-large wp-image-22104\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Swb-17-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Swb-17-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Swb-17-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Swb-17-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Swb-17-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43a1b37 elementor-widget elementor-widget-text-editor\" data-id=\"43a1b37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta bogatobia\u0142kowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ee7192f\" data-id=\"ee7192f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eabba96 elementor-widget elementor-widget-image\" data-id=\"eabba96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Sdp-17-1024x768.jpg\" class=\"attachment-large size-large wp-image-22107\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Sdp-17-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Sdp-17-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Sdp-17-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Sdp-17-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Sdp-17-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c6caa8 elementor-widget elementor-widget-text-editor\" data-id=\"7c6caa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta podstawowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a76af0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a76af0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c45a84c\" data-id=\"c45a84c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9a11c2 elementor-widget elementor-widget-heading\" data-id=\"d9a11c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Obiad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-397dd4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"397dd4a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-78139a1\" data-id=\"78139a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b35b8c elementor-widget elementor-widget-image\" data-id=\"1b35b8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Owb-17-1024x768.jpg\" class=\"attachment-large size-large wp-image-22106\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Owb-17-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Owb-17-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Owb-17-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Owb-17-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Owb-17-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0ca302 elementor-widget elementor-widget-text-editor\" data-id=\"b0ca302\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta bogatobia\u0142kowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2ad3117\" data-id=\"2ad3117\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6c07ab elementor-widget elementor-widget-image\" data-id=\"a6c07ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Odp-17-1024x768.jpg\" class=\"attachment-large size-large wp-image-22105\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Odp-17-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Odp-17-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Odp-17-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Odp-17-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Odp-17-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-714c4ff elementor-widget elementor-widget-text-editor\" data-id=\"714c4ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta podstawowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u015aniadanie Dieta bogatobia\u0142kowa Dieta podstawowa Obiad Dieta bogatobia\u0142kowa Dieta podstawowa<\/p>\n","protected":false},"author":1,"featured_media":22104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"footnotes":""},"categories":[47],"tags":[],"class_list":["post-22102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-posilki"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posi\u0142ek w dniu 2024-04-25 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posi\u0142ek w dniu 2024-04-25 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\" \/>\n<meta property=\"og:description\" content=\"\u015aniadanie Dieta bogatobia\u0142kowa Dieta podstawowa Obiad Dieta bogatobia\u0142kowa Dieta podstawowa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-25T11:39:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-26T12:18:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Swb-17-rotated.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Krzysztof Kasprzyk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Krzysztof Kasprzyk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2024\\\/04\\\/25\\\/posilek-w-dniu-2024-04-25\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2024\\\/04\\\/25\\\/posilek-w-dniu-2024-04-25\\\/\"},\"author\":{\"name\":\"Krzysztof Kasprzyk\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/person\\\/88ad471b758c11e595bd87abceaf3cfd\"},\"headline\":\"Posi\u0142ek w dniu 2024-04-25\",\"datePublished\":\"2024-04-25T11:39:43+00:00\",\"dateModified\":\"2024-04-26T12:18:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2024\\\/04\\\/25\\\/posilek-w-dniu-2024-04-25\\\/\"},\"wordCount\":18,\"publisher\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2024\\\/04\\\/25\\\/posilek-w-dniu-2024-04-25\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Swb-17-rotated.jpg\",\"articleSection\":[\"Posi\u0142ki\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2024\\\/04\\\/25\\\/posilek-w-dniu-2024-04-25\\\/\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2024\\\/04\\\/25\\\/posilek-w-dniu-2024-04-25\\\/\",\"name\":\"Posi\u0142ek w dniu 2024-04-25 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2024\\\/04\\\/25\\\/posilek-w-dniu-2024-04-25\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2024\\\/04\\\/25\\\/posilek-w-dniu-2024-04-25\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Swb-17-rotated.jpg\",\"datePublished\":\"2024-04-25T11:39:43+00:00\",\"dateModified\":\"2024-04-26T12:18:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2024\\\/04\\\/25\\\/posilek-w-dniu-2024-04-25\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2024\\\/04\\\/25\\\/posilek-w-dniu-2024-04-25\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2024\\\/04\\\/25\\\/posilek-w-dniu-2024-04-25\\\/#primaryimage\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Swb-17-rotated.jpg\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Swb-17-rotated.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2024\\\/04\\\/25\\\/posilek-w-dniu-2024-04-25\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/czerwonagora.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posi\u0142ek w dniu 2024-04-25\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#website\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/\",\"name\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"description\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"publisher\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/czerwonagora.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\",\"name\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-WSS-DUZE-transparentne.png\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-WSS-DUZE-transparentne.png\",\"width\":4210,\"height\":2975,\"caption\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SzpitalCzerwonaGora\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/person\\\/88ad471b758c11e595bd87abceaf3cfd\",\"name\":\"Krzysztof Kasprzyk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/758f42868e3c503ca9f38bee50fcfff3.jpg?ver=1778590642\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/758f42868e3c503ca9f38bee50fcfff3.jpg?ver=1778590642\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/758f42868e3c503ca9f38bee50fcfff3.jpg?ver=1778590642\",\"caption\":\"Krzysztof Kasprzyk\"},\"sameAs\":[\"https:\\\/\\\/czerwonagora.pl\"],\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/author\\\/maverick\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posi\u0142ek w dniu 2024-04-25 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/","og_locale":"pl_PL","og_type":"article","og_title":"Posi\u0142ek w dniu 2024-04-25 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","og_description":"\u015aniadanie Dieta bogatobia\u0142kowa Dieta podstawowa Obiad Dieta bogatobia\u0142kowa Dieta podstawowa","og_url":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/","og_site_name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","article_publisher":"https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/","article_published_time":"2024-04-25T11:39:43+00:00","article_modified_time":"2024-04-26T12:18:51+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Swb-17-rotated.jpg","type":"image\/jpeg"}],"author":"Krzysztof Kasprzyk","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Krzysztof Kasprzyk","Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/#article","isPartOf":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/"},"author":{"name":"Krzysztof Kasprzyk","@id":"https:\/\/czerwonagora.pl\/#\/schema\/person\/88ad471b758c11e595bd87abceaf3cfd"},"headline":"Posi\u0142ek w dniu 2024-04-25","datePublished":"2024-04-25T11:39:43+00:00","dateModified":"2024-04-26T12:18:51+00:00","mainEntityOfPage":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/"},"wordCount":18,"publisher":{"@id":"https:\/\/czerwonagora.pl\/#organization"},"image":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/#primaryimage"},"thumbnailUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Swb-17-rotated.jpg","articleSection":["Posi\u0142ki"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/","url":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/","name":"Posi\u0142ek w dniu 2024-04-25 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","isPartOf":{"@id":"https:\/\/czerwonagora.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/#primaryimage"},"image":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/#primaryimage"},"thumbnailUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Swb-17-rotated.jpg","datePublished":"2024-04-25T11:39:43+00:00","dateModified":"2024-04-26T12:18:51+00:00","breadcrumb":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/#primaryimage","url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Swb-17-rotated.jpg","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2024\/04\/Swb-17-rotated.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/czerwonagora.pl\/index.php\/2024\/04\/25\/posilek-w-dniu-2024-04-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/czerwonagora.pl\/"},{"@type":"ListItem","position":2,"name":"Posi\u0142ek w dniu 2024-04-25"}]},{"@type":"WebSite","@id":"https:\/\/czerwonagora.pl\/#website","url":"https:\/\/czerwonagora.pl\/","name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","description":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","publisher":{"@id":"https:\/\/czerwonagora.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/czerwonagora.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/czerwonagora.pl\/#organization","name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","url":"https:\/\/czerwonagora.pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/#\/schema\/logo\/image\/","url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2021\/06\/Logo-WSS-DUZE-transparentne.png","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2021\/06\/Logo-WSS-DUZE-transparentne.png","width":4210,"height":2975,"caption":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze"},"image":{"@id":"https:\/\/czerwonagora.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/"]},{"@type":"Person","@id":"https:\/\/czerwonagora.pl\/#\/schema\/person\/88ad471b758c11e595bd87abceaf3cfd","name":"Krzysztof Kasprzyk","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/758f42868e3c503ca9f38bee50fcfff3.jpg?ver=1778590642","url":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/758f42868e3c503ca9f38bee50fcfff3.jpg?ver=1778590642","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/758f42868e3c503ca9f38bee50fcfff3.jpg?ver=1778590642","caption":"Krzysztof Kasprzyk"},"sameAs":["https:\/\/czerwonagora.pl"],"url":"https:\/\/czerwonagora.pl\/index.php\/author\/maverick\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:23:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/22102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/comments?post=22102"}],"version-history":[{"count":7,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/22102\/revisions"}],"predecessor-version":[{"id":22121,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/22102\/revisions\/22121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/media\/22104"}],"wp:attachment":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/media?parent=22102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/categories?post=22102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/tags?post=22102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}