{"id":28617,"date":"2025-07-22T13:58:27","date_gmt":"2025-07-22T11:58:27","guid":{"rendered":"https:\/\/czerwonagora.pl\/?p=28617"},"modified":"2025-07-22T13:59:41","modified_gmt":"2025-07-22T11:59:41","slug":"posilek-w-dniu-2025-07-22","status":"publish","type":"post","link":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/","title":{"rendered":"Posi\u0142ek w dniu 2025-07-22"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"28617\" class=\"elementor elementor-28617\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9a6f01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9a6f01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9cf779e\" data-id=\"9cf779e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b29e7e6 elementor-widget elementor-widget-heading\" data-id=\"b29e7e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u015aniadanie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bf171bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf171bb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dac5635\" data-id=\"dac5635\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c04b10 elementor-widget elementor-widget-image\" data-id=\"7c04b10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-1-1024x768.jpg\" class=\"attachment-large size-large wp-image-28623\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-1-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-1-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-1-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-1-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-1-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f08a9e8 elementor-widget elementor-widget-text-editor\" data-id=\"f08a9e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta podstawowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f240d6e\" data-id=\"f240d6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-395b529 elementor-widget elementor-widget-image\" data-id=\"395b529\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-latwostrawna-z-ograniczeniem-tluszczu-1-1024x768.jpg\" class=\"attachment-large size-large wp-image-28624\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-latwostrawna-z-ograniczeniem-tluszczu-1-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-latwostrawna-z-ograniczeniem-tluszczu-1-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-latwostrawna-z-ograniczeniem-tluszczu-1-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-latwostrawna-z-ograniczeniem-tluszczu-1-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-latwostrawna-z-ograniczeniem-tluszczu-1-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1e5f0e elementor-widget elementor-widget-text-editor\" data-id=\"e1e5f0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d0875a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0875a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-409392d\" data-id=\"409392d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4087ead elementor-widget elementor-widget-heading\" data-id=\"4087ead\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Obiad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-14ddf7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14ddf7f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3e8495d\" data-id=\"3e8495d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e553d8 elementor-widget elementor-widget-image\" data-id=\"2e553d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-Obiad-1024x771.jpg\" class=\"attachment-large size-large wp-image-28621\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-Obiad-1024x771.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-Obiad-300x226.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-Obiad-768x578.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-Obiad-1536x1156.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-Obiad.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df3650e elementor-widget elementor-widget-text-editor\" data-id=\"df3650e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta podstawowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b3b8f9\" data-id=\"6b3b8f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bf917a elementor-widget elementor-widget-image\" data-id=\"3bf917a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-latwostrawna-z-ograniczeniem-tluszczu-2-1024x771.jpg\" class=\"attachment-large size-large wp-image-28622\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-latwostrawna-z-ograniczeniem-tluszczu-2-1024x771.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-latwostrawna-z-ograniczeniem-tluszczu-2-300x226.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-latwostrawna-z-ograniczeniem-tluszczu-2-768x578.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-latwostrawna-z-ograniczeniem-tluszczu-2-1536x1156.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-latwostrawna-z-ograniczeniem-tluszczu-2.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-828510c elementor-widget elementor-widget-text-editor\" data-id=\"828510c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u015aniadanie Dieta podstawowa Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu Obiad Dieta podstawowa Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu<\/p>\n","protected":false},"author":10,"featured_media":28623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"footnotes":""},"categories":[47],"tags":[],"class_list":["post-28617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-posilki"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posi\u0142ek w dniu 2025-07-22 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posi\u0142ek w dniu 2025-07-22 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\" \/>\n<meta property=\"og:description\" content=\"\u015aniadanie Dieta podstawowa Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu Obiad Dieta podstawowa Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/\" \/>\n<meta property=\"og:site_name\" content=\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-22T11:58:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-22T11:59:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-1-rotated.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bart\u0142omiej Jedli\u0144ski\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bart\u0142omiej Jedli\u0144ski\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/07\\\/22\\\/posilek-w-dniu-2025-07-22\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/07\\\/22\\\/posilek-w-dniu-2025-07-22\\\/\"},\"author\":{\"name\":\"Bart\u0142omiej Jedli\u0144ski\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/person\\\/1adf7587b0acdf004ec6caf0c67ff5de\"},\"headline\":\"Posi\u0142ek w dniu 2025-07-22\",\"datePublished\":\"2025-07-22T11:58:27+00:00\",\"dateModified\":\"2025-07-22T11:59:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/07\\\/22\\\/posilek-w-dniu-2025-07-22\\\/\"},\"wordCount\":24,\"publisher\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/07\\\/22\\\/posilek-w-dniu-2025-07-22\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Dieta-podstawowa-1-rotated.jpg\",\"articleSection\":[\"Posi\u0142ki\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/07\\\/22\\\/posilek-w-dniu-2025-07-22\\\/\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/07\\\/22\\\/posilek-w-dniu-2025-07-22\\\/\",\"name\":\"Posi\u0142ek w dniu 2025-07-22 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/07\\\/22\\\/posilek-w-dniu-2025-07-22\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/07\\\/22\\\/posilek-w-dniu-2025-07-22\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Dieta-podstawowa-1-rotated.jpg\",\"datePublished\":\"2025-07-22T11:58:27+00:00\",\"dateModified\":\"2025-07-22T11:59:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/07\\\/22\\\/posilek-w-dniu-2025-07-22\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/07\\\/22\\\/posilek-w-dniu-2025-07-22\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/07\\\/22\\\/posilek-w-dniu-2025-07-22\\\/#primaryimage\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Dieta-podstawowa-1-rotated.jpg\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Dieta-podstawowa-1-rotated.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/07\\\/22\\\/posilek-w-dniu-2025-07-22\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/czerwonagora.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posi\u0142ek w dniu 2025-07-22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#website\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/\",\"name\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"description\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"publisher\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/czerwonagora.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\",\"name\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-WSS-DUZE-transparentne.png\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-WSS-DUZE-transparentne.png\",\"width\":4210,\"height\":2975,\"caption\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SzpitalCzerwonaGora\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/person\\\/1adf7587b0acdf004ec6caf0c67ff5de\",\"name\":\"Bart\u0142omiej Jedli\u0144ski\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/ab3195b2fdb8ba6c0efb654f2908993d.jpg?ver=1778590846\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/ab3195b2fdb8ba6c0efb654f2908993d.jpg?ver=1778590846\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/ab3195b2fdb8ba6c0efb654f2908993d.jpg?ver=1778590846\",\"caption\":\"Bart\u0142omiej Jedli\u0144ski\"},\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/author\\\/jedlinski\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posi\u0142ek w dniu 2025-07-22 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/","og_locale":"pl_PL","og_type":"article","og_title":"Posi\u0142ek w dniu 2025-07-22 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","og_description":"\u015aniadanie Dieta podstawowa Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu Obiad Dieta podstawowa Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu","og_url":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/","og_site_name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","article_publisher":"https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/","article_published_time":"2025-07-22T11:58:27+00:00","article_modified_time":"2025-07-22T11:59:41+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-1-rotated.jpg","type":"image\/jpeg"}],"author":"Bart\u0142omiej Jedli\u0144ski","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Bart\u0142omiej Jedli\u0144ski","Szacowany czas czytania":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/#article","isPartOf":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/"},"author":{"name":"Bart\u0142omiej Jedli\u0144ski","@id":"https:\/\/czerwonagora.pl\/#\/schema\/person\/1adf7587b0acdf004ec6caf0c67ff5de"},"headline":"Posi\u0142ek w dniu 2025-07-22","datePublished":"2025-07-22T11:58:27+00:00","dateModified":"2025-07-22T11:59:41+00:00","mainEntityOfPage":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/"},"wordCount":24,"publisher":{"@id":"https:\/\/czerwonagora.pl\/#organization"},"image":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/#primaryimage"},"thumbnailUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-1-rotated.jpg","articleSection":["Posi\u0142ki"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/","url":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/","name":"Posi\u0142ek w dniu 2025-07-22 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","isPartOf":{"@id":"https:\/\/czerwonagora.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/#primaryimage"},"image":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/#primaryimage"},"thumbnailUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-1-rotated.jpg","datePublished":"2025-07-22T11:58:27+00:00","dateModified":"2025-07-22T11:59:41+00:00","breadcrumb":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/#primaryimage","url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-1-rotated.jpg","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/07\/Dieta-podstawowa-1-rotated.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/07\/22\/posilek-w-dniu-2025-07-22\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/czerwonagora.pl\/"},{"@type":"ListItem","position":2,"name":"Posi\u0142ek w dniu 2025-07-22"}]},{"@type":"WebSite","@id":"https:\/\/czerwonagora.pl\/#website","url":"https:\/\/czerwonagora.pl\/","name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","description":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","publisher":{"@id":"https:\/\/czerwonagora.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/czerwonagora.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/czerwonagora.pl\/#organization","name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","url":"https:\/\/czerwonagora.pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/#\/schema\/logo\/image\/","url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2021\/06\/Logo-WSS-DUZE-transparentne.png","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2021\/06\/Logo-WSS-DUZE-transparentne.png","width":4210,"height":2975,"caption":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze"},"image":{"@id":"https:\/\/czerwonagora.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/"]},{"@type":"Person","@id":"https:\/\/czerwonagora.pl\/#\/schema\/person\/1adf7587b0acdf004ec6caf0c67ff5de","name":"Bart\u0142omiej Jedli\u0144ski","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/ab3195b2fdb8ba6c0efb654f2908993d.jpg?ver=1778590846","url":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/ab3195b2fdb8ba6c0efb654f2908993d.jpg?ver=1778590846","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/ab3195b2fdb8ba6c0efb654f2908993d.jpg?ver=1778590846","caption":"Bart\u0142omiej Jedli\u0144ski"},"url":"https:\/\/czerwonagora.pl\/index.php\/author\/jedlinski\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:46:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/28617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/comments?post=28617"}],"version-history":[{"count":4,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/28617\/revisions"}],"predecessor-version":[{"id":28627,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/28617\/revisions\/28627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/media\/28623"}],"wp:attachment":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/media?parent=28617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/categories?post=28617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/tags?post=28617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}