{"id":29179,"date":"2025-09-04T13:48:06","date_gmt":"2025-09-04T11:48:06","guid":{"rendered":"https:\/\/czerwonagora.pl\/?p=29179"},"modified":"2025-09-04T13:48:08","modified_gmt":"2025-09-04T11:48:08","slug":"posilek-w-dniu-2025-09-04","status":"publish","type":"post","link":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/","title":{"rendered":"Posi\u0142ek w dniu 2025-09-04"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"29179\" class=\"elementor elementor-29179\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa42ca5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa42ca5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28af147\" data-id=\"28af147\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58f3891 elementor-widget elementor-widget-heading\" data-id=\"58f3891\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u015aniadanie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-24f6d0a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24f6d0a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a8f25ba\" data-id=\"a8f25ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ebe458 elementor-widget elementor-widget-image\" data-id=\"4ebe458\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-11-1024x768.jpg\" class=\"attachment-large size-large wp-image-29184\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-11-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-11-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-11-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-11-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-11-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b9a175 elementor-widget elementor-widget-text-editor\" data-id=\"4b9a175\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta podstawowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eae177d\" data-id=\"eae177d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c45c3f elementor-widget elementor-widget-image\" data-id=\"5c45c3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-22-1024x768.jpg\" class=\"attachment-large size-large wp-image-29185\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-22-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-22-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-22-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-22-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-22.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17159b4 elementor-widget elementor-widget-text-editor\" data-id=\"17159b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-222cd66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"222cd66\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9b84b9\" data-id=\"e9b84b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f98b386 elementor-widget elementor-widget-heading\" data-id=\"f98b386\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Obiad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eb11a9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb11a9f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-607146e\" data-id=\"607146e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d62a20b elementor-widget elementor-widget-image\" data-id=\"d62a20b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"808\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-33-1024x808.jpg\" class=\"attachment-large size-large wp-image-29189\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-33-1024x808.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-33-300x237.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-33-768x606.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-33-1536x1212.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-33.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a16c90a elementor-widget elementor-widget-text-editor\" data-id=\"a16c90a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta podstawowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3c2bed2\" data-id=\"3c2bed2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b606ba5 elementor-widget elementor-widget-image\" data-id=\"b606ba5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"787\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-44-1024x787.jpg\" class=\"attachment-large size-large wp-image-29190\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-44-1024x787.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-44-300x231.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-44-768x590.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-44-1536x1181.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-44.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d05738b elementor-widget elementor-widget-text-editor\" data-id=\"d05738b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u015aniadanie Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w Obiad Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w<\/p>\n","protected":false},"author":12,"featured_media":29190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"footnotes":""},"categories":[47],"tags":[],"class_list":["post-29179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-posilki"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posi\u0142ek w dniu 2025-09-04 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posi\u0142ek w dniu 2025-09-04 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\" \/>\n<meta property=\"og:description\" content=\"\u015aniadanie Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w Obiad Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w\" \/>\n<meta property=\"og:url\" content=\"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/\" \/>\n<meta property=\"og:site_name\" content=\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-04T11:48:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-04T11:48:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-44.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1230\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miko\u0142aj Miko\u0142ajczyk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miko\u0142aj Miko\u0142ajczyk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/04\\\/posilek-w-dniu-2025-09-04\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/04\\\/posilek-w-dniu-2025-09-04\\\/\"},\"author\":{\"name\":\"Miko\u0142aj Miko\u0142ajczyk\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/person\\\/4a2cd8ea4e10435b2c65e0c6e9f4738b\"},\"headline\":\"Posi\u0142ek w dniu 2025-09-04\",\"datePublished\":\"2025-09-04T11:48:06+00:00\",\"dateModified\":\"2025-09-04T11:48:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/04\\\/posilek-w-dniu-2025-09-04\\\/\"},\"wordCount\":28,\"publisher\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/04\\\/posilek-w-dniu-2025-09-04\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/04-44.jpg\",\"articleSection\":[\"Posi\u0142ki\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/04\\\/posilek-w-dniu-2025-09-04\\\/\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/04\\\/posilek-w-dniu-2025-09-04\\\/\",\"name\":\"Posi\u0142ek w dniu 2025-09-04 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/04\\\/posilek-w-dniu-2025-09-04\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/04\\\/posilek-w-dniu-2025-09-04\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/04-44.jpg\",\"datePublished\":\"2025-09-04T11:48:06+00:00\",\"dateModified\":\"2025-09-04T11:48:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/04\\\/posilek-w-dniu-2025-09-04\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/04\\\/posilek-w-dniu-2025-09-04\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/04\\\/posilek-w-dniu-2025-09-04\\\/#primaryimage\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/04-44.jpg\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/04-44.jpg\",\"width\":1600,\"height\":1230},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/04\\\/posilek-w-dniu-2025-09-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/czerwonagora.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posi\u0142ek w dniu 2025-09-04\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#website\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/\",\"name\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"description\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"publisher\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/czerwonagora.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\",\"name\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-WSS-DUZE-transparentne.png\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-WSS-DUZE-transparentne.png\",\"width\":4210,\"height\":2975,\"caption\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SzpitalCzerwonaGora\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/person\\\/4a2cd8ea4e10435b2c65e0c6e9f4738b\",\"name\":\"Miko\u0142aj Miko\u0142ajczyk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094\",\"caption\":\"Miko\u0142aj Miko\u0142ajczyk\"},\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/author\\\/mikolajczyk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posi\u0142ek w dniu 2025-09-04 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/","og_locale":"pl_PL","og_type":"article","og_title":"Posi\u0142ek w dniu 2025-09-04 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","og_description":"\u015aniadanie Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w Obiad Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w","og_url":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/","og_site_name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","article_publisher":"https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/","article_published_time":"2025-09-04T11:48:06+00:00","article_modified_time":"2025-09-04T11:48:08+00:00","og_image":[{"width":1600,"height":1230,"url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-44.jpg","type":"image\/jpeg"}],"author":"Miko\u0142aj Miko\u0142ajczyk","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Miko\u0142aj Miko\u0142ajczyk","Szacowany czas czytania":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/#article","isPartOf":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/"},"author":{"name":"Miko\u0142aj Miko\u0142ajczyk","@id":"https:\/\/czerwonagora.pl\/#\/schema\/person\/4a2cd8ea4e10435b2c65e0c6e9f4738b"},"headline":"Posi\u0142ek w dniu 2025-09-04","datePublished":"2025-09-04T11:48:06+00:00","dateModified":"2025-09-04T11:48:08+00:00","mainEntityOfPage":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/"},"wordCount":28,"publisher":{"@id":"https:\/\/czerwonagora.pl\/#organization"},"image":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/#primaryimage"},"thumbnailUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-44.jpg","articleSection":["Posi\u0142ki"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/","url":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/","name":"Posi\u0142ek w dniu 2025-09-04 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","isPartOf":{"@id":"https:\/\/czerwonagora.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/#primaryimage"},"image":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/#primaryimage"},"thumbnailUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-44.jpg","datePublished":"2025-09-04T11:48:06+00:00","dateModified":"2025-09-04T11:48:08+00:00","breadcrumb":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/#primaryimage","url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-44.jpg","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/04-44.jpg","width":1600,"height":1230},{"@type":"BreadcrumbList","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/04\/posilek-w-dniu-2025-09-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/czerwonagora.pl\/"},{"@type":"ListItem","position":2,"name":"Posi\u0142ek w dniu 2025-09-04"}]},{"@type":"WebSite","@id":"https:\/\/czerwonagora.pl\/#website","url":"https:\/\/czerwonagora.pl\/","name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","description":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","publisher":{"@id":"https:\/\/czerwonagora.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/czerwonagora.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/czerwonagora.pl\/#organization","name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","url":"https:\/\/czerwonagora.pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/#\/schema\/logo\/image\/","url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2021\/06\/Logo-WSS-DUZE-transparentne.png","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2021\/06\/Logo-WSS-DUZE-transparentne.png","width":4210,"height":2975,"caption":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze"},"image":{"@id":"https:\/\/czerwonagora.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/"]},{"@type":"Person","@id":"https:\/\/czerwonagora.pl\/#\/schema\/person\/4a2cd8ea4e10435b2c65e0c6e9f4738b","name":"Miko\u0142aj Miko\u0142ajczyk","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094","url":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094","caption":"Miko\u0142aj Miko\u0142ajczyk"},"url":"https:\/\/czerwonagora.pl\/index.php\/author\/mikolajczyk\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:34:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/29179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/comments?post=29179"}],"version-history":[{"count":11,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/29179\/revisions"}],"predecessor-version":[{"id":29194,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/29179\/revisions\/29194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/media\/29190"}],"wp:attachment":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/media?parent=29179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/categories?post=29179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/tags?post=29179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}