{"id":29355,"date":"2025-09-19T13:24:06","date_gmt":"2025-09-19T11:24:06","guid":{"rendered":"https:\/\/czerwonagora.pl\/?p=29355"},"modified":"2025-09-19T13:26:06","modified_gmt":"2025-09-19T11:26:06","slug":"posilek-w-dniu-2025-09-19","status":"publish","type":"post","link":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/","title":{"rendered":"Posi\u0142ek w dniu 2025-09-19"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"29355\" class=\"elementor elementor-29355\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4fdd9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4fdd9d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c19185\" data-id=\"9c19185\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a699c73 elementor-widget elementor-widget-heading\" data-id=\"a699c73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u015aniadanie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-16b5545 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16b5545\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f9fd309\" data-id=\"f9fd309\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a08acc9 elementor-widget elementor-widget-image\" data-id=\"a08acc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-1-1024x768.jpg\" class=\"attachment-large size-large wp-image-29357\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-1-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-1-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-1-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-1-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-1-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-378f8ad elementor-widget elementor-widget-text-editor\" data-id=\"378f8ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta podstawowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b8400a5\" data-id=\"b8400a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3683497 elementor-widget elementor-widget-image\" data-id=\"3683497\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-2-1024x768.jpg\" class=\"attachment-large size-large wp-image-29358\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-2-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-2-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-2-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-2-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-2-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea0b74c elementor-widget elementor-widget-text-editor\" data-id=\"ea0b74c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-560b204 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"560b204\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38e093e\" data-id=\"38e093e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7727d83 elementor-widget elementor-widget-heading\" data-id=\"7727d83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Obiad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b25125f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b25125f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-459e390\" data-id=\"459e390\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a06dcca elementor-widget elementor-widget-image\" data-id=\"a06dcca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"794\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-3-1024x794.jpg\" class=\"attachment-large size-large wp-image-29359\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-3-1024x794.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-3-300x233.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-3-768x595.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-3-1536x1190.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-3.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e51300c elementor-widget elementor-widget-text-editor\" data-id=\"e51300c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta podstawowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1f1a999\" data-id=\"1f1a999\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55889b5 elementor-widget elementor-widget-image\" data-id=\"55889b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-4-1024x771.jpg\" class=\"attachment-large size-large wp-image-29360\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-4-1024x771.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-4-300x226.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-4-768x578.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-4-1536x1156.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-4.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed24434 elementor-widget elementor-widget-text-editor\" data-id=\"ed24434\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u015aniadanie Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w Obiad Dieta podstawowa Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu<\/p>\n","protected":false},"author":12,"featured_media":29359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"footnotes":""},"categories":[47],"tags":[],"class_list":["post-29355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-posilki"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posi\u0142ek w dniu 2025-09-19 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posi\u0142ek w dniu 2025-09-19 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\" \/>\n<meta property=\"og:description\" content=\"\u015aniadanie Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w Obiad Dieta podstawowa Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-19T11:24:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-19T11:26:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miko\u0142aj Miko\u0142ajczyk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miko\u0142aj Miko\u0142ajczyk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/19\\\/posilek-w-dniu-2025-09-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/19\\\/posilek-w-dniu-2025-09-19\\\/\"},\"author\":{\"name\":\"Miko\u0142aj Miko\u0142ajczyk\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/person\\\/4a2cd8ea4e10435b2c65e0c6e9f4738b\"},\"headline\":\"Posi\u0142ek w dniu 2025-09-19\",\"datePublished\":\"2025-09-19T11:24:06+00:00\",\"dateModified\":\"2025-09-19T11:26:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/19\\\/posilek-w-dniu-2025-09-19\\\/\"},\"wordCount\":26,\"publisher\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/19\\\/posilek-w-dniu-2025-09-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-3.jpg\",\"articleSection\":[\"Posi\u0142ki\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/19\\\/posilek-w-dniu-2025-09-19\\\/\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/19\\\/posilek-w-dniu-2025-09-19\\\/\",\"name\":\"Posi\u0142ek w dniu 2025-09-19 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/19\\\/posilek-w-dniu-2025-09-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/19\\\/posilek-w-dniu-2025-09-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-3.jpg\",\"datePublished\":\"2025-09-19T11:24:06+00:00\",\"dateModified\":\"2025-09-19T11:26:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/19\\\/posilek-w-dniu-2025-09-19\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/19\\\/posilek-w-dniu-2025-09-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/19\\\/posilek-w-dniu-2025-09-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-3.jpg\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/19-3.jpg\",\"width\":1600,\"height\":1240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/09\\\/19\\\/posilek-w-dniu-2025-09-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/czerwonagora.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posi\u0142ek w dniu 2025-09-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#website\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/\",\"name\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"description\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"publisher\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/czerwonagora.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\",\"name\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-WSS-DUZE-transparentne.png\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-WSS-DUZE-transparentne.png\",\"width\":4210,\"height\":2975,\"caption\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SzpitalCzerwonaGora\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/person\\\/4a2cd8ea4e10435b2c65e0c6e9f4738b\",\"name\":\"Miko\u0142aj Miko\u0142ajczyk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094\",\"caption\":\"Miko\u0142aj Miko\u0142ajczyk\"},\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/author\\\/mikolajczyk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posi\u0142ek w dniu 2025-09-19 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/","og_locale":"pl_PL","og_type":"article","og_title":"Posi\u0142ek w dniu 2025-09-19 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","og_description":"\u015aniadanie Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w Obiad Dieta podstawowa Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu","og_url":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/","og_site_name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","article_publisher":"https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/","article_published_time":"2025-09-19T11:24:06+00:00","article_modified_time":"2025-09-19T11:26:06+00:00","og_image":[{"width":1600,"height":1240,"url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-3.jpg","type":"image\/jpeg"}],"author":"Miko\u0142aj Miko\u0142ajczyk","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Miko\u0142aj Miko\u0142ajczyk","Szacowany czas czytania":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/#article","isPartOf":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/"},"author":{"name":"Miko\u0142aj Miko\u0142ajczyk","@id":"https:\/\/czerwonagora.pl\/#\/schema\/person\/4a2cd8ea4e10435b2c65e0c6e9f4738b"},"headline":"Posi\u0142ek w dniu 2025-09-19","datePublished":"2025-09-19T11:24:06+00:00","dateModified":"2025-09-19T11:26:06+00:00","mainEntityOfPage":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/"},"wordCount":26,"publisher":{"@id":"https:\/\/czerwonagora.pl\/#organization"},"image":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/#primaryimage"},"thumbnailUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-3.jpg","articleSection":["Posi\u0142ki"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/","url":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/","name":"Posi\u0142ek w dniu 2025-09-19 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","isPartOf":{"@id":"https:\/\/czerwonagora.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/#primaryimage"},"image":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/#primaryimage"},"thumbnailUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-3.jpg","datePublished":"2025-09-19T11:24:06+00:00","dateModified":"2025-09-19T11:26:06+00:00","breadcrumb":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/#primaryimage","url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-3.jpg","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/09\/19-3.jpg","width":1600,"height":1240},{"@type":"BreadcrumbList","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/09\/19\/posilek-w-dniu-2025-09-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/czerwonagora.pl\/"},{"@type":"ListItem","position":2,"name":"Posi\u0142ek w dniu 2025-09-19"}]},{"@type":"WebSite","@id":"https:\/\/czerwonagora.pl\/#website","url":"https:\/\/czerwonagora.pl\/","name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","description":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","publisher":{"@id":"https:\/\/czerwonagora.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/czerwonagora.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/czerwonagora.pl\/#organization","name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","url":"https:\/\/czerwonagora.pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/#\/schema\/logo\/image\/","url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2021\/06\/Logo-WSS-DUZE-transparentne.png","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2021\/06\/Logo-WSS-DUZE-transparentne.png","width":4210,"height":2975,"caption":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze"},"image":{"@id":"https:\/\/czerwonagora.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/"]},{"@type":"Person","@id":"https:\/\/czerwonagora.pl\/#\/schema\/person\/4a2cd8ea4e10435b2c65e0c6e9f4738b","name":"Miko\u0142aj Miko\u0142ajczyk","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094","url":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094","caption":"Miko\u0142aj Miko\u0142ajczyk"},"url":"https:\/\/czerwonagora.pl\/index.php\/author\/mikolajczyk\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:31:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/29355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/comments?post=29355"}],"version-history":[{"count":4,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/29355\/revisions"}],"predecessor-version":[{"id":29363,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/29355\/revisions\/29363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/media\/29359"}],"wp:attachment":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/media?parent=29355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/categories?post=29355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/tags?post=29355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}