{"id":29853,"date":"2025-10-29T14:29:56","date_gmt":"2025-10-29T13:29:56","guid":{"rendered":"https:\/\/czerwonagora.pl\/?p=29853"},"modified":"2025-10-29T14:29:57","modified_gmt":"2025-10-29T13:29:57","slug":"posilek-w-dniu-2025-10-29-2","status":"publish","type":"post","link":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/","title":{"rendered":"Posi\u0142ek w dniu 2025-10-29"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"29853\" class=\"elementor elementor-29853\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15fc0bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15fc0bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc9499c\" data-id=\"cc9499c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1560c59 elementor-widget elementor-widget-heading\" data-id=\"1560c59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u015aniadanie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-92229c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92229c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dc377cb\" data-id=\"dc377cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c89a5a elementor-widget elementor-widget-image\" data-id=\"9c89a5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-11-1024x768.jpg\" class=\"attachment-large size-large wp-image-29855\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-11-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-11-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-11-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-11-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-11-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c1013b elementor-widget elementor-widget-text-editor\" data-id=\"9c1013b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta podstawowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c234a18\" data-id=\"c234a18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-818033b elementor-widget elementor-widget-image\" data-id=\"818033b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"793\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-22-1024x793.jpg\" class=\"attachment-large size-large wp-image-29856\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-22-1024x793.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-22-300x232.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-22-768x595.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-22-1536x1189.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-22-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34b03ce elementor-widget elementor-widget-text-editor\" data-id=\"34b03ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d48f786 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d48f786\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7dda1cf\" data-id=\"7dda1cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95582a7 elementor-widget elementor-widget-heading\" data-id=\"95582a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Obiad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-da15026 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da15026\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ca61685\" data-id=\"ca61685\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d08a93 elementor-widget elementor-widget-image\" data-id=\"3d08a93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"804\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-33-1024x804.jpg\" class=\"attachment-large size-large wp-image-29857\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-33-1024x804.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-33-300x236.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-33-768x603.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-33-1536x1206.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-33.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff4f681 elementor-widget elementor-widget-text-editor\" data-id=\"ff4f681\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta podstawowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-98b7deb\" data-id=\"98b7deb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed750d1 elementor-widget elementor-widget-image\" data-id=\"ed750d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"804\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-44-1024x804.jpg\" class=\"attachment-large size-large wp-image-29858\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-44-1024x804.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-44-300x236.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-44-768x603.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-44-1536x1207.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-44.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-356c608 elementor-widget elementor-widget-text-editor\" data-id=\"356c608\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u015aniadanie Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w Obiad Dieta podstawowa Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu<\/p>\n","protected":false},"author":12,"featured_media":29858,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"footnotes":""},"categories":[47],"tags":[],"class_list":["post-29853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-posilki"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posi\u0142ek w dniu 2025-10-29 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posi\u0142ek w dniu 2025-10-29 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\" \/>\n<meta property=\"og:description\" content=\"\u015aniadanie Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w Obiad Dieta podstawowa Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-29T13:29:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T13:29:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-44.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1257\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miko\u0142aj Miko\u0142ajczyk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miko\u0142aj Miko\u0142ajczyk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/10\\\/29\\\/posilek-w-dniu-2025-10-29-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/10\\\/29\\\/posilek-w-dniu-2025-10-29-2\\\/\"},\"author\":{\"name\":\"Miko\u0142aj Miko\u0142ajczyk\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/person\\\/4a2cd8ea4e10435b2c65e0c6e9f4738b\"},\"headline\":\"Posi\u0142ek w dniu 2025-10-29\",\"datePublished\":\"2025-10-29T13:29:56+00:00\",\"dateModified\":\"2025-10-29T13:29:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/10\\\/29\\\/posilek-w-dniu-2025-10-29-2\\\/\"},\"wordCount\":26,\"publisher\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/10\\\/29\\\/posilek-w-dniu-2025-10-29-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/29-44.jpg\",\"articleSection\":[\"Posi\u0142ki\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/10\\\/29\\\/posilek-w-dniu-2025-10-29-2\\\/\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/10\\\/29\\\/posilek-w-dniu-2025-10-29-2\\\/\",\"name\":\"Posi\u0142ek w dniu 2025-10-29 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/10\\\/29\\\/posilek-w-dniu-2025-10-29-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/10\\\/29\\\/posilek-w-dniu-2025-10-29-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/29-44.jpg\",\"datePublished\":\"2025-10-29T13:29:56+00:00\",\"dateModified\":\"2025-10-29T13:29:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/10\\\/29\\\/posilek-w-dniu-2025-10-29-2\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/10\\\/29\\\/posilek-w-dniu-2025-10-29-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/10\\\/29\\\/posilek-w-dniu-2025-10-29-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/29-44.jpg\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/29-44.jpg\",\"width\":1600,\"height\":1257},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/10\\\/29\\\/posilek-w-dniu-2025-10-29-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/czerwonagora.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posi\u0142ek w dniu 2025-10-29\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#website\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/\",\"name\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"description\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"publisher\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/czerwonagora.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\",\"name\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-WSS-DUZE-transparentne.png\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-WSS-DUZE-transparentne.png\",\"width\":4210,\"height\":2975,\"caption\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SzpitalCzerwonaGora\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/person\\\/4a2cd8ea4e10435b2c65e0c6e9f4738b\",\"name\":\"Miko\u0142aj Miko\u0142ajczyk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094\",\"caption\":\"Miko\u0142aj Miko\u0142ajczyk\"},\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/author\\\/mikolajczyk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posi\u0142ek w dniu 2025-10-29 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/","og_locale":"pl_PL","og_type":"article","og_title":"Posi\u0142ek w dniu 2025-10-29 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","og_description":"\u015aniadanie Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w Obiad Dieta podstawowa Dieta \u0142atwostrawna z ograniczeniem t\u0142uszczu","og_url":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/","og_site_name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","article_publisher":"https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/","article_published_time":"2025-10-29T13:29:56+00:00","article_modified_time":"2025-10-29T13:29:57+00:00","og_image":[{"width":1600,"height":1257,"url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-44.jpg","type":"image\/jpeg"}],"author":"Miko\u0142aj Miko\u0142ajczyk","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Miko\u0142aj Miko\u0142ajczyk","Szacowany czas czytania":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/#article","isPartOf":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/"},"author":{"name":"Miko\u0142aj Miko\u0142ajczyk","@id":"https:\/\/czerwonagora.pl\/#\/schema\/person\/4a2cd8ea4e10435b2c65e0c6e9f4738b"},"headline":"Posi\u0142ek w dniu 2025-10-29","datePublished":"2025-10-29T13:29:56+00:00","dateModified":"2025-10-29T13:29:57+00:00","mainEntityOfPage":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/"},"wordCount":26,"publisher":{"@id":"https:\/\/czerwonagora.pl\/#organization"},"image":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/#primaryimage"},"thumbnailUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-44.jpg","articleSection":["Posi\u0142ki"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/","url":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/","name":"Posi\u0142ek w dniu 2025-10-29 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","isPartOf":{"@id":"https:\/\/czerwonagora.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/#primaryimage"},"image":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/#primaryimage"},"thumbnailUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-44.jpg","datePublished":"2025-10-29T13:29:56+00:00","dateModified":"2025-10-29T13:29:57+00:00","breadcrumb":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/#primaryimage","url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-44.jpg","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/10\/29-44.jpg","width":1600,"height":1257},{"@type":"BreadcrumbList","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/10\/29\/posilek-w-dniu-2025-10-29-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/czerwonagora.pl\/"},{"@type":"ListItem","position":2,"name":"Posi\u0142ek w dniu 2025-10-29"}]},{"@type":"WebSite","@id":"https:\/\/czerwonagora.pl\/#website","url":"https:\/\/czerwonagora.pl\/","name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","description":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","publisher":{"@id":"https:\/\/czerwonagora.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/czerwonagora.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/czerwonagora.pl\/#organization","name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","url":"https:\/\/czerwonagora.pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/#\/schema\/logo\/image\/","url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2021\/06\/Logo-WSS-DUZE-transparentne.png","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2021\/06\/Logo-WSS-DUZE-transparentne.png","width":4210,"height":2975,"caption":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze"},"image":{"@id":"https:\/\/czerwonagora.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/"]},{"@type":"Person","@id":"https:\/\/czerwonagora.pl\/#\/schema\/person\/4a2cd8ea4e10435b2c65e0c6e9f4738b","name":"Miko\u0142aj Miko\u0142ajczyk","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094","url":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094","caption":"Miko\u0142aj Miko\u0142ajczyk"},"url":"https:\/\/czerwonagora.pl\/index.php\/author\/mikolajczyk\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:49:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/29853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/comments?post=29853"}],"version-history":[{"count":4,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/29853\/revisions"}],"predecessor-version":[{"id":29861,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/29853\/revisions\/29861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/media\/29858"}],"wp:attachment":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/media?parent=29853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/categories?post=29853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/tags?post=29853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}