{"id":30350,"date":"2025-11-25T07:41:47","date_gmt":"2025-11-25T06:41:47","guid":{"rendered":"https:\/\/czerwonagora.pl\/?p=30350"},"modified":"2025-11-26T07:56:02","modified_gmt":"2025-11-26T06:56:02","slug":"posilek-w-dniu-2025-11-25","status":"publish","type":"post","link":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/","title":{"rendered":"Posi\u0142ek w dniu 2025-11-25"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"30350\" class=\"elementor elementor-30350\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c7c0fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c7c0fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a83ff72\" data-id=\"a83ff72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f904bcb elementor-widget elementor-widget-heading\" data-id=\"f904bcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u015aniadanie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a43b4fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a43b4fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ca23f72\" data-id=\"ca23f72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b23009b elementor-widget elementor-widget-image\" data-id=\"b23009b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-11-1024x768.jpg\" class=\"attachment-large size-large wp-image-30353\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-11-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-11-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-11-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-11-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-11.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fec83c elementor-widget elementor-widget-text-editor\" data-id=\"9fec83c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta podstawowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-125e647\" data-id=\"125e647\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05a58f1 elementor-widget elementor-widget-image\" data-id=\"05a58f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-22-1024x768.jpg\" class=\"attachment-large size-large wp-image-30354\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-22-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-22-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-22-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-22-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-22-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8776232 elementor-widget elementor-widget-text-editor\" data-id=\"8776232\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7b6c7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7b6c7f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dae0b94\" data-id=\"dae0b94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36dc14b elementor-widget elementor-widget-heading\" data-id=\"36dc14b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Obiad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-38faa5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38faa5a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a7c8c78\" data-id=\"a7c8c78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71070c9 elementor-widget elementor-widget-image\" data-id=\"71070c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-33-1024x768.jpg\" class=\"attachment-large size-large wp-image-30355\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-33-1024x768.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-33-300x225.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-33-768x576.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-33-1536x1152.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-33-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f82057 elementor-widget elementor-widget-text-editor\" data-id=\"6f82057\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta podstawowa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ed5835e\" data-id=\"ed5835e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-703111e elementor-widget elementor-widget-image\" data-id=\"703111e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"787\" src=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-44-1024x787.jpg\" class=\"attachment-large size-large wp-image-30356\" alt=\"\" srcset=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-44-1024x787.jpg 1024w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-44-300x230.jpg 300w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-44-768x590.jpg 768w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-44-1536x1180.jpg 1536w, https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-44-rotated.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35c9f15 elementor-widget elementor-widget-text-editor\" data-id=\"35c9f15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u015aniadanie Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w Obiad Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w<\/p>\n","protected":false},"author":12,"featured_media":30356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"footnotes":""},"categories":[47],"tags":[],"class_list":["post-30350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-posilki"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posi\u0142ek w dniu 2025-11-25 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posi\u0142ek w dniu 2025-11-25 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\" \/>\n<meta property=\"og:description\" content=\"\u015aniadanie Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w Obiad Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w\" \/>\n<meta property=\"og:url\" content=\"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-25T06:41:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T06:56:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-44-rotated.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1229\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miko\u0142aj Miko\u0142ajczyk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miko\u0142aj Miko\u0142ajczyk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/11\\\/25\\\/posilek-w-dniu-2025-11-25\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/11\\\/25\\\/posilek-w-dniu-2025-11-25\\\/\"},\"author\":{\"name\":\"Miko\u0142aj Miko\u0142ajczyk\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/person\\\/4a2cd8ea4e10435b2c65e0c6e9f4738b\"},\"headline\":\"Posi\u0142ek w dniu 2025-11-25\",\"datePublished\":\"2025-11-25T06:41:47+00:00\",\"dateModified\":\"2025-11-26T06:56:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/11\\\/25\\\/posilek-w-dniu-2025-11-25\\\/\"},\"wordCount\":28,\"publisher\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/11\\\/25\\\/posilek-w-dniu-2025-11-25\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/26-44-rotated.jpg\",\"articleSection\":[\"Posi\u0142ki\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/11\\\/25\\\/posilek-w-dniu-2025-11-25\\\/\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/11\\\/25\\\/posilek-w-dniu-2025-11-25\\\/\",\"name\":\"Posi\u0142ek w dniu 2025-11-25 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/11\\\/25\\\/posilek-w-dniu-2025-11-25\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/11\\\/25\\\/posilek-w-dniu-2025-11-25\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/26-44-rotated.jpg\",\"datePublished\":\"2025-11-25T06:41:47+00:00\",\"dateModified\":\"2025-11-26T06:56:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/11\\\/25\\\/posilek-w-dniu-2025-11-25\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/11\\\/25\\\/posilek-w-dniu-2025-11-25\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/11\\\/25\\\/posilek-w-dniu-2025-11-25\\\/#primaryimage\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/26-44-rotated.jpg\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/26-44-rotated.jpg\",\"width\":1600,\"height\":1229},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/2025\\\/11\\\/25\\\/posilek-w-dniu-2025-11-25\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/czerwonagora.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posi\u0142ek w dniu 2025-11-25\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#website\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/\",\"name\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"description\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"publisher\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/czerwonagora.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#organization\",\"name\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-WSS-DUZE-transparentne.png\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-WSS-DUZE-transparentne.png\",\"width\":4210,\"height\":2975,\"caption\":\"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze\"},\"image\":{\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SzpitalCzerwonaGora\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/#\\\/schema\\\/person\\\/4a2cd8ea4e10435b2c65e0c6e9f4738b\",\"name\":\"Miko\u0142aj Miko\u0142ajczyk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094\",\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094\",\"contentUrl\":\"https:\\\/\\\/czerwonagora.pl\\\/wp-content\\\/litespeed\\\/avatar\\\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094\",\"caption\":\"Miko\u0142aj Miko\u0142ajczyk\"},\"url\":\"https:\\\/\\\/czerwonagora.pl\\\/index.php\\\/author\\\/mikolajczyk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posi\u0142ek w dniu 2025-11-25 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/","og_locale":"pl_PL","og_type":"article","og_title":"Posi\u0142ek w dniu 2025-11-25 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","og_description":"\u015aniadanie Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w Obiad Dieta podstawowa Dieta z ograniczeniem \u0142atwo przyswajalnych w\u0119glowodan\u00f3w","og_url":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/","og_site_name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","article_publisher":"https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/","article_published_time":"2025-11-25T06:41:47+00:00","article_modified_time":"2025-11-26T06:56:02+00:00","og_image":[{"width":1600,"height":1229,"url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-44-rotated.jpg","type":"image\/jpeg"}],"author":"Miko\u0142aj Miko\u0142ajczyk","twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"Miko\u0142aj Miko\u0142ajczyk","Szacowany czas czytania":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/#article","isPartOf":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/"},"author":{"name":"Miko\u0142aj Miko\u0142ajczyk","@id":"https:\/\/czerwonagora.pl\/#\/schema\/person\/4a2cd8ea4e10435b2c65e0c6e9f4738b"},"headline":"Posi\u0142ek w dniu 2025-11-25","datePublished":"2025-11-25T06:41:47+00:00","dateModified":"2025-11-26T06:56:02+00:00","mainEntityOfPage":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/"},"wordCount":28,"publisher":{"@id":"https:\/\/czerwonagora.pl\/#organization"},"image":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/#primaryimage"},"thumbnailUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-44-rotated.jpg","articleSection":["Posi\u0142ki"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/","url":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/","name":"Posi\u0142ek w dniu 2025-11-25 - Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","isPartOf":{"@id":"https:\/\/czerwonagora.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/#primaryimage"},"image":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/#primaryimage"},"thumbnailUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-44-rotated.jpg","datePublished":"2025-11-25T06:41:47+00:00","dateModified":"2025-11-26T06:56:02+00:00","breadcrumb":{"@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/#primaryimage","url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-44-rotated.jpg","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2025\/11\/26-44-rotated.jpg","width":1600,"height":1229},{"@type":"BreadcrumbList","@id":"https:\/\/czerwonagora.pl\/index.php\/2025\/11\/25\/posilek-w-dniu-2025-11-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/czerwonagora.pl\/"},{"@type":"ListItem","position":2,"name":"Posi\u0142ek w dniu 2025-11-25"}]},{"@type":"WebSite","@id":"https:\/\/czerwonagora.pl\/#website","url":"https:\/\/czerwonagora.pl\/","name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","description":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","publisher":{"@id":"https:\/\/czerwonagora.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/czerwonagora.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/czerwonagora.pl\/#organization","name":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze","url":"https:\/\/czerwonagora.pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/#\/schema\/logo\/image\/","url":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2021\/06\/Logo-WSS-DUZE-transparentne.png","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/uploads\/2021\/06\/Logo-WSS-DUZE-transparentne.png","width":4210,"height":2975,"caption":"Wojew\u00f3dzki Szpital Specjalistyczny im. \u015aw. Rafa\u0142a w Czerwonej G\u00f3rze"},"image":{"@id":"https:\/\/czerwonagora.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SzpitalCzerwonaGora\/"]},{"@type":"Person","@id":"https:\/\/czerwonagora.pl\/#\/schema\/person\/4a2cd8ea4e10435b2c65e0c6e9f4738b","name":"Miko\u0142aj Miko\u0142ajczyk","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094","url":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094","contentUrl":"https:\/\/czerwonagora.pl\/wp-content\/litespeed\/avatar\/48ed4d719e5e64e3df35aeef2956d77c.jpg?ver=1778589094","caption":"Miko\u0142aj Miko\u0142ajczyk"},"url":"https:\/\/czerwonagora.pl\/index.php\/author\/mikolajczyk\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:00:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/30350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/comments?post=30350"}],"version-history":[{"count":5,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/30350\/revisions"}],"predecessor-version":[{"id":30360,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/posts\/30350\/revisions\/30360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/media\/30356"}],"wp:attachment":[{"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/media?parent=30350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/categories?post=30350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/czerwonagora.pl\/index.php\/wp-json\/wp\/v2\/tags?post=30350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}